{"id":1165,"date":"2018-06-15T16:57:20","date_gmt":"2018-06-15T16:57:20","guid":{"rendered":"http:\/\/www.ecolibri.it\/?p=1165"},"modified":"2018-06-21T12:24:51","modified_gmt":"2018-06-21T12:24:51","slug":"ecolibri-dona-energia-ad-un-resort-in-mozambico","status":"publish","type":"post","link":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/","title":{"rendered":"L&#8217;energia di un Resort"},"content":{"rendered":"<p>L&#8217;energia di un Resort<\/p>\n<p>Intervistato da GQ Italia \u00a0Filipe Carneiro, consulente legale e commerciale di Ecolibr\u00ec, racconta della collaborazione con il resort Coral Lodge in Mozambico e del progetto per renderlo\u00a0energicamente\u00a0autonomo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1163\" src=\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort-.jpg\" alt=\"\" width=\"4867\" height=\"3259\" \/><\/p>\n<p>Qui l&#8217;articolo stampa:<\/p>\n<p><a href=\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Energia-per-un-Resort.pdf\">Coral Lodge Energia per un Resort<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;energia di un Resort Intervistato da GQ Italia \u00a0Filipe Carneiro, consulente legale e commerciale di Ecolibr\u00ec, racconta della collaborazione con il resort Coral Lodge in Mozambico e del progetto per renderlo\u00a0energicamente\u00a0autonomo. Qui l&#8217;articolo stampa: Coral Lodge Energia per un Resort &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1165","post","type-post","status-publish","format-standard","hentry","category-rassegna-stampa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;energia di un Resort | eColibri<\/title>\n<meta name=\"description\" content=\"L&#039;energia di un Resort: tutte le news dal mondo di Ecolibr\u00ec e dell&#039;energia rinnovabile\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;energia di un Resort | eColibri\" \/>\n<meta property=\"og:description\" content=\"L&#039;energia di un Resort: tutte le news dal mondo di Ecolibr\u00ec e dell&#039;energia rinnovabile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/\" \/>\n<meta property=\"og:site_name\" content=\"eColibri\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-15T16:57:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-21T12:24:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort--scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Petra Rothe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Petra Rothe\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/\"},\"author\":{\"name\":\"Petra Rothe\",\"@id\":\"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477\"},\"headline\":\"L&#8217;energia di un Resort\",\"datePublished\":\"2018-06-15T16:57:20+00:00\",\"dateModified\":\"2018-06-21T12:24:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/\"},\"wordCount\":47,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort-.jpg\",\"articleSection\":[\"Rassegna Stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/\",\"url\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/\",\"name\":\"L'energia di un Resort | eColibri\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecolibri.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort-.jpg\",\"datePublished\":\"2018-06-15T16:57:20+00:00\",\"dateModified\":\"2018-06-21T12:24:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477\"},\"description\":\"L'energia di un Resort: tutte le news dal mondo di Ecolibr\u00ec e dell'energia rinnovabile\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#primaryimage\",\"url\":\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort-.jpg\",\"contentUrl\":\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort-.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecolibri.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;energia di un Resort\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecolibri.it\/#website\",\"url\":\"https:\/\/www.ecolibri.it\/\",\"name\":\"eColibri\",\"description\":\"Power of Nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecolibri.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477\",\"name\":\"Petra Rothe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ecolibri.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5ecc1d2ad924d7fa57f2e26c50cb6ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5ecc1d2ad924d7fa57f2e26c50cb6ec?s=96&d=mm&r=g\",\"caption\":\"Petra Rothe\"},\"sameAs\":[\"http:\/\/www.ecolibri.it\"],\"url\":\"https:\/\/www.ecolibri.it\/it\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'energia di un Resort | eColibri","description":"L'energia di un Resort: tutte le news dal mondo di Ecolibr\u00ec e dell'energia rinnovabile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/","og_locale":"it_IT","og_type":"article","og_title":"L'energia di un Resort | eColibri","og_description":"L'energia di un Resort: tutte le news dal mondo di Ecolibr\u00ec e dell'energia rinnovabile","og_url":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/","og_site_name":"eColibri","article_published_time":"2018-06-15T16:57:20+00:00","article_modified_time":"2018-06-21T12:24:51+00:00","og_image":[{"width":2560,"height":1714,"url":"https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort--scaled.jpg","type":"image\/jpeg"}],"author":"Petra Rothe","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Petra Rothe"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#article","isPartOf":{"@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/"},"author":{"name":"Petra Rothe","@id":"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477"},"headline":"L&#8217;energia di un Resort","datePublished":"2018-06-15T16:57:20+00:00","dateModified":"2018-06-21T12:24:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/"},"wordCount":47,"commentCount":0,"image":{"@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort-.jpg","articleSection":["Rassegna Stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/","url":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/","name":"L'energia di un Resort | eColibri","isPartOf":{"@id":"https:\/\/www.ecolibri.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#primaryimage"},"image":{"@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort-.jpg","datePublished":"2018-06-15T16:57:20+00:00","dateModified":"2018-06-21T12:24:51+00:00","author":{"@id":"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477"},"description":"L'energia di un Resort: tutte le news dal mondo di Ecolibr\u00ec e dell'energia rinnovabile","breadcrumb":{"@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#primaryimage","url":"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort-.jpg","contentUrl":"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/06\/Coral-Lodge-Lenergia-di-un-Resort-.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecolibri.it\/it\/ecolibri-dona-energia-ad-un-resort-in-mozambico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecolibri.it\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;energia di un Resort"}]},{"@type":"WebSite","@id":"https:\/\/www.ecolibri.it\/#website","url":"https:\/\/www.ecolibri.it\/","name":"eColibri","description":"Power of Nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecolibri.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477","name":"Petra Rothe","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ecolibri.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5ecc1d2ad924d7fa57f2e26c50cb6ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5ecc1d2ad924d7fa57f2e26c50cb6ec?s=96&d=mm&r=g","caption":"Petra Rothe"},"sameAs":["http:\/\/www.ecolibri.it"],"url":"https:\/\/www.ecolibri.it\/it\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/posts\/1165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/comments?post=1165"}],"version-history":[{"count":4,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/posts\/1165\/revisions"}],"predecessor-version":[{"id":1180,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/posts\/1165\/revisions\/1180"}],"wp:attachment":[{"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/media?parent=1165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/categories?post=1165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/tags?post=1165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}