{"id":1233,"date":"2018-07-09T12:36:22","date_gmt":"2018-07-09T12:36:22","guid":{"rendered":"http:\/\/www.ecolibri.it\/?p=1233"},"modified":"2018-07-09T12:38:26","modified_gmt":"2018-07-09T12:38:26","slug":"conde-nast-traveller-presenta-il-coral-lodge","status":"publish","type":"post","link":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/","title":{"rendered":"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge"},"content":{"rendered":"<p>Il prestigioso giornale COND\u00c9 NAST TRAVELLER , il quale attraverso i suoi reportage fotografici, consente ai lettori di vivere le emozioni provate dai grandi viaggiatori, presenta il Coral Lodge in Mozambico, dove Ecolibr\u00ec fornisce l&#8217;energia elettrica per rendere il soggiorno ecosostenibile.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1232\" src=\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Cond\u00e9-Nast-Traveller-Luglio-2018-Eng.jpg\" alt=\"\" width=\"1240\" height=\"1754\" srcset=\"https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Cond\u00e9-Nast-Traveller-Luglio-2018-Eng.jpg 1240w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Cond\u00e9-Nast-Traveller-Luglio-2018-Eng-212x300.jpg 212w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Cond\u00e9-Nast-Traveller-Luglio-2018-Eng-724x1024.jpg 724w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Cond\u00e9-Nast-Traveller-Luglio-2018-Eng-768x1086.jpg 768w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Cond\u00e9-Nast-Traveller-Luglio-2018-Eng-1086x1536.jpg 1086w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Cond\u00e9-Nast-Traveller-Luglio-2018-Eng-14x20.jpg 14w\" sizes=\"auto, (max-width: 1240px) 100vw, 1240px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1234\" src=\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg\" alt=\"\" width=\"1058\" height=\"768\" srcset=\"https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg 1058w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018-600x436.jpg 600w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018-300x218.jpg 300w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018-1024x743.jpg 1024w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018-768x557.jpg 768w, https:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018-20x15.jpg 20w\" sizes=\"auto, (max-width: 1058px) 100vw, 1058px\" \/><\/p>\n<p><a href=\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-Luglio-2018-IT.pdf\">Coral Lodge Hospitality Luglio 2018 IT<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il prestigioso giornale COND\u00c9 NAST TRAVELLER , il quale attraverso i suoi reportage fotografici, consente ai lettori di vivere le emozioni provate dai grandi viaggiatori, presenta il Coral Lodge in Mozambico, dove Ecolibr\u00ec fornisce l&#8217;energia elettrica per rendere il soggiorno ecosostenibile. Coral Lodge Hospitality Luglio 2018 IT &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1233","post","type-post","status-publish","format-standard","hentry","category-rassegna-stampa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COND\u00c9 NAST TRAVELLER presenta il Coral Lodge | eColibri<\/title>\n<meta name=\"description\" content=\"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge: tutte le news dal mondo di Ecolibr\u00ec e dell&#039;energia rinnovabile\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge | eColibri\" \/>\n<meta property=\"og:description\" content=\"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge: tutte le news dal mondo di Ecolibr\u00ec e dell&#039;energia rinnovabile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/\" \/>\n<meta property=\"og:site_name\" content=\"eColibri\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-09T12:36:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-09T12:38:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Cond\u00e9-Nast-Traveller-Luglio-2018-Eng.jpg\" \/>\n<meta name=\"author\" content=\"Petra Rothe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Petra Rothe\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/\"},\"author\":{\"name\":\"Petra Rothe\",\"@id\":\"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477\"},\"headline\":\"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge\",\"datePublished\":\"2018-07-09T12:36:22+00:00\",\"dateModified\":\"2018-07-09T12:38:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/\"},\"wordCount\":53,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg\",\"articleSection\":[\"Rassegna Stampa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/\",\"url\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/\",\"name\":\"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge | eColibri\",\"isPartOf\":{\"@id\":\"https:\/\/www.ecolibri.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg\",\"datePublished\":\"2018-07-09T12:36:22+00:00\",\"dateModified\":\"2018-07-09T12:38:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477\"},\"description\":\"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge: tutte le news dal mondo di Ecolibr\u00ec e dell'energia rinnovabile\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#primaryimage\",\"url\":\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg\",\"contentUrl\":\"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ecolibri.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ecolibri.it\/#website\",\"url\":\"https:\/\/www.ecolibri.it\/\",\"name\":\"eColibri\",\"description\":\"Power of Nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ecolibri.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477\",\"name\":\"Petra Rothe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.ecolibri.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5ecc1d2ad924d7fa57f2e26c50cb6ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5ecc1d2ad924d7fa57f2e26c50cb6ec?s=96&d=mm&r=g\",\"caption\":\"Petra Rothe\"},\"sameAs\":[\"http:\/\/www.ecolibri.it\"],\"url\":\"https:\/\/www.ecolibri.it\/it\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge | eColibri","description":"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge: tutte le news dal mondo di Ecolibr\u00ec e dell'energia rinnovabile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/","og_locale":"it_IT","og_type":"article","og_title":"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge | eColibri","og_description":"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge: tutte le news dal mondo di Ecolibr\u00ec e dell'energia rinnovabile","og_url":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/","og_site_name":"eColibri","article_published_time":"2018-07-09T12:36:22+00:00","article_modified_time":"2018-07-09T12:38:26+00:00","og_image":[{"url":"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Cond\u00e9-Nast-Traveller-Luglio-2018-Eng.jpg","type":"","width":"","height":""}],"author":"Petra Rothe","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Petra Rothe"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#article","isPartOf":{"@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/"},"author":{"name":"Petra Rothe","@id":"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477"},"headline":"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge","datePublished":"2018-07-09T12:36:22+00:00","dateModified":"2018-07-09T12:38:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/"},"wordCount":53,"commentCount":0,"image":{"@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg","articleSection":["Rassegna Stampa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/","url":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/","name":"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge | eColibri","isPartOf":{"@id":"https:\/\/www.ecolibri.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#primaryimage"},"image":{"@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg","datePublished":"2018-07-09T12:36:22+00:00","dateModified":"2018-07-09T12:38:26+00:00","author":{"@id":"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477"},"description":"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge: tutte le news dal mondo di Ecolibr\u00ec e dell'energia rinnovabile","breadcrumb":{"@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#primaryimage","url":"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg","contentUrl":"http:\/\/www.ecolibri.it\/wp-content\/uploads\/2018\/07\/Coral-Lodge-Hospitality-IT-Luglio-2018.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ecolibri.it\/it\/conde-nast-traveller-presenta-il-coral-lodge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ecolibri.it\/it\/"},{"@type":"ListItem","position":2,"name":"COND\u00c9 NAST TRAVELLER presenta il Coral Lodge"}]},{"@type":"WebSite","@id":"https:\/\/www.ecolibri.it\/#website","url":"https:\/\/www.ecolibri.it\/","name":"eColibri","description":"Power of Nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ecolibri.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.ecolibri.it\/#\/schema\/person\/a1f94b60e877d4362ab8d1d588065477","name":"Petra Rothe","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ecolibri.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5ecc1d2ad924d7fa57f2e26c50cb6ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5ecc1d2ad924d7fa57f2e26c50cb6ec?s=96&d=mm&r=g","caption":"Petra Rothe"},"sameAs":["http:\/\/www.ecolibri.it"],"url":"https:\/\/www.ecolibri.it\/it\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/posts\/1233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/comments?post=1233"}],"version-history":[{"count":3,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/posts\/1233\/revisions"}],"predecessor-version":[{"id":1238,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/posts\/1233\/revisions\/1238"}],"wp:attachment":[{"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/media?parent=1233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/categories?post=1233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecolibri.it\/it\/wp-json\/wp\/v2\/tags?post=1233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}